{"id":2,"date":"2026-06-02T09:11:34","date_gmt":"2026-06-02T07:11:34","guid":{"rendered":"https:\/\/apymeco.netrotec.com\/?page_id=2"},"modified":"2026-06-23T09:22:27","modified_gmt":"2026-06-23T07:22:27","slug":"inicio","status":"publish","type":"page","link":"https:\/\/apymeco.netrotec.com\/en\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2\" class=\"elementor elementor-2\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea73d2d e-con-full e-flex e-con e-parent\" data-id=\"ea73d2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10b71d7 elementor-widget elementor-widget-layerslider\" data-id=\"10b71d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"layerslider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">jQuery(function() { _initLayerSlider( '#layerslider_1_13bswih3zxeen', {sliderVersion: '8.2.0', type: 'fullwidth', allowFullscreen: true, pauseOnHover: 'enabled', skin: 'v6', sliderFadeInDuration: 350, showCircleTimer: false, allowRestartOnResize: true, useSrcset: true, skinsPath: 'https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/LayerSlider\/assets\/static\/layerslider\/skins\/', performanceMode: true}); });<\/script><link href=\"https:\/\/fonts.googleapis.com\/css?family=Montserrat:100,100i,200,200i,300,300i,400,400i,500,500i,600,600i,700,700i,800,800i,900,900i%7CNunito:100,100i,200,200i,300,300i,400,400i,500,500i,600,600i,700,700i,800,800i,900,900i\" rel=\"stylesheet\"><div id=\"layerslider_1_13bswih3zxeen\"  class=\"ls-wp-container fitvidsignore ls-selectable\" style=\"width:1280px;height:720px;margin:0 auto;margin-bottom: 0px;\"><div class=\"ls-slide\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png\" class=\"ls-bg\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png 1920w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky-300x169.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky-1024x576.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky-768x432.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky-1536x864.png 1536w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky-18x10.png 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/slide-1-1.jpg\" class=\"ls-tn\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/slide-1-1.jpg 640w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/slide-1-1-300x169.jpg 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/slide-1-1-18x10.jpg 18w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><img decoding=\"async\" width=\"600\" height=\"555\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/f29c331be3cffcab0c17179f1dd02499.png\" class=\"ls-l ls-img-layer\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/f29c331be3cffcab0c17179f1dd02499.png 600w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/f29c331be3cffcab0c17179f1dd02499-300x278.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/f29c331be3cffcab0c17179f1dd02499-13x12.png 13w\" sizes=\"(max-width: 600px) 100vw, 600px\" style=\"filter: blur(3px);top:25%;left:110%;text-align:initial;width:233px;height:216px;opacity:.95;\" data-ls=\"showinfo:1;loop:true;loopoffsetx:-120sw;loopduration:55000;loopstartat:allinend + 4000;loopcount:-1;parallax:true;parallaxlevel:-4;parallaxevent:scroll;parallaxdurationmove:750;position:fixed;\"><img loading=\"lazy\" decoding=\"async\" width=\"398\" height=\"509\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/6-balloon-rainbow_1.png\" class=\"ls-l ls-img-layer\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/6-balloon-rainbow_1.png 398w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/6-balloon-rainbow_1-235x300.png 235w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/6-balloon-rainbow_1-9x12.png 9w\" sizes=\"(max-width: 398px) 100vw, 398px\" style=\"top:35%;left:115%;text-align:initial;width:261px;height:335px;\" data-ls=\"showinfo:1;durationin:1;loop:true;loopoffsetx:-130sw;loopduration:35000;loopstartat:allinend + 0;loopcount:-1;parallax:true;parallaxlevel:-7;parallaxevent:scroll;parallaxdurationmove:750;position:fixed;\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"480\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-scaled.png\" class=\"ls-l ls-img-layer\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-scaled.png 2560w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-300x56.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-1024x192.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-768x144.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-1536x288.png 1536w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-2048x384.png 2048w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-back-18x3.png 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"top:70%;left:0px;text-align:initial;\" data-ls=\"showinfo:1;durationin:2000;loop:true;loopoffsetx:-1920;loopduration:60000;loopstartat:transitioninstart + 0;loopcount:-1;parallax:true;parallaxlevel:5;parallaxaxis:y;position:fixed;\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"480\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-scaled.png\" class=\"ls-l ls-img-layer\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-scaled.png 2560w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-300x56.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-1024x192.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-768x144.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-1536x288.png 1536w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-2048x384.png 2048w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-middle-18x3.png 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"top:70%;left:0px;text-align:initial;\" data-ls=\"showinfo:1;durationin:2000;loop:true;loopoffsetx:-1920;loopduration:35000;loopstartat:transitioninstart + 0;loopcount:-1;parallax:true;parallaxaxis:y;position:fixed;\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"480\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-scaled.png\" class=\"ls-l ls-img-layer\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-scaled.png 2560w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-300x56.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-1024x192.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-768x144.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-1536x288.png 1536w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-2048x384.png 2048w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/clouds-front-18x3.png 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"top:80%;left:0px;text-align:initial;\" data-ls=\"showinfo:1;durationin:2000;loop:true;loopoffsetx:-1920;loopduration:15000;loopstartat:transitioninstart + 0;loopcount:-1;parallax:true;parallaxlevel:15;parallaxaxis:y;position:fixed;\"><p style=\"top:50%;left:50%;text-align:initial;color:#001e37;font-family:Nunito;opacity:.85;font-size:100px;padding-top:10px;padding-right:25px;padding-bottom:0px;padding-left:25px;border-width:0px 0px 4px 0px;border-color:#001e37;\" class=\"ls-l ls-text-layer\" data-ls=\"showinfo:1;delayin:1000;fadein:false;clipin:0 100% 0 0;texttransitionin:true;texttypein:chars_rand;textdurationin:1500;texteasingin:easeOutElastic;textfadein:false;textrotatein:20|-20|-20|20;textrotateyin:90|-90;textscalexin:1.3;textscaleyin:1.3;loop:true;loopoffsety:120;loopduration:750;loopstartat:transitioninend + 1000;loopeasing:easeInOutQuint;looprotate:-90;loopscalex:.5;loopscaley:.5;looptransformorigin:left bottom 0;loopcount:1;parallax:true;parallaxlevel:-10;parallaxevent:scroll;parallaxdurationmove:750;position:relative;\">APYMECO TORREVIEJA<\/p><p style=\"text-shadow: 0px 0px 50px rgba(255,255,255,.4);top:50%;left:37.12%;text-align:initial;opacity:.85;color:#001e37;font-size:300px;font-family:Montserrat;line-height:400px;height:400px;\" class=\"ls-l ls-text-layer\" data-ls=\"showinfo:1;offsetxin:-100lw;delayin:3200;clipin:0 0 0 100%;loop:true;loopduration:4000;loopeasing:easeInOutQuint;loopscalex:1.1;loopscaley:1.1;loopcount:-1;loopyoyo:true;parallax:true;parallaxlevel:-10;parallaxevent:scroll;parallaxdurationmove:750;position:relative;\">+30<\/p><p style=\"top:250px;left:743px;text-align:initial;font-family:montserrat;font-size:180px;color:rgba(255,255,255,.85);;\" class=\"ls-l ls-text-layer\" data-ls=\"showinfo:1;transitionin:false;texttransitionin:true;texttypein:chars_asc;textshiftin:250;texteasingin:easeOutBack;textstartatin:transitioninend + 4200;textrotateyin:-90;parallax:true;parallaxlevel:-10;parallaxevent:scroll;parallaxdurationmove:750;position:relative;\">A\u00d1OS<\/p><p style=\"letter-spacing: 20px;top:491px;left:107px;text-align:right;font-weight:300;font-family:montserrat;font-size:50px;color:#001e37;opacity:.75;\" class=\"ls-l ls-text-layer\" data-ls=\"showinfo:1;transitionin:false;texttransitionin:true;texttypein:chars_edge;textdurationin:600;texteasingin:easeOutBack;textstartatin:transitioninend + 5000;textrotatein:random(-90,90);parallax:true;parallaxlevel:-10;parallaxevent:scroll;parallaxdurationmove:750;position:relative;\">elevando nuestro comercio<br>\na lo m\u00e1s alto<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c02a66 e-con-full e-flex e-con e-parent\" data-id=\"4c02a66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fccce3 elementor-widget elementor-widget-directorist_search_listing\" data-id=\"8fccce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"directorist_search_listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"directorist-search-contents directorist-contents-wrap\" data-atts=\"{&quot;show_title_subtitle&quot;:&quot;yes&quot;,&quot;search_bar_title&quot;:&quot;Buscar establecimientos&quot;,&quot;search_bar_sub_title&quot;:&quot;\\u00a1Todo lo que necesitas, en tu comercio local!&quot;,&quot;search_button&quot;:&quot;yes&quot;,&quot;search_button_text&quot;:&quot;Buscar&quot;,&quot;more_filters_button&quot;:&quot;&quot;,&quot;more_filters_text&quot;:null,&quot;reset_filters_button&quot;:null,&quot;apply_filters_button&quot;:null,&quot;reset_filters_text&quot;:null,&quot;apply_filters_text&quot;:null,&quot;logged_in_user_only&quot;:&quot;no&quot;,&quot;redirect_page_url&quot;:&quot;&quot;,&quot;more_filters_display&quot;:&quot;sliding&quot;,&quot;directory_type&quot;:&quot;&quot;,&quot;default_directory_type&quot;:&quot;&quot;,&quot;show_popular_category&quot;:&quot;&quot;}\">\n\n    <div class=\"directorist-container-fluid\">\n\n        \n        \n            <div class=\"directorist-search-top\">\n\n                                    <h2 class=\"directorist-search-top__title\">Buscar establecimientos<\/h2>\n                \n                                    <p class=\"directorist-search-top__subtitle\">\u00a1Todo lo que necesitas, en tu comercio local!<\/p>\n                \n            <\/div>\n\n        \n        <form action=\"https:\/\/apymeco.netrotec.com\/en\/resultados-de-la-busqueda-2\/\" class=\"directorist-search-form\" data-atts=\"{&quot;show_title_subtitle&quot;:&quot;yes&quot;,&quot;search_bar_title&quot;:&quot;Buscar establecimientos&quot;,&quot;search_bar_sub_title&quot;:&quot;\\u00a1Todo lo que necesitas, en tu comercio local!&quot;,&quot;search_button&quot;:&quot;yes&quot;,&quot;search_button_text&quot;:&quot;Buscar&quot;,&quot;more_filters_button&quot;:&quot;&quot;,&quot;more_filters_text&quot;:null,&quot;reset_filters_button&quot;:null,&quot;apply_filters_button&quot;:null,&quot;reset_filters_text&quot;:null,&quot;apply_filters_text&quot;:null,&quot;logged_in_user_only&quot;:&quot;no&quot;,&quot;redirect_page_url&quot;:&quot;&quot;,&quot;more_filters_display&quot;:&quot;sliding&quot;,&quot;directory_type&quot;:&quot;&quot;,&quot;default_directory_type&quot;:&quot;&quot;,&quot;show_popular_category&quot;:&quot;&quot;}\">\n\n            <div class=\"directorist-search-form-wrap directorist-search-form__wrap directorist-with-search-border\">\n\n                \n                <input type=\"hidden\" name=\"directory_type\" class=\"listing_type\" value=\"business\">\n\n                \n<div class=\"directorist-search-form__box\">\n\n    <div class=\"directorist-search-form-top directorist-flex directorist-align-center directorist-search-form-inline directorist-search-form__top\">\n        \n<div class=\"directorist-search-adv-filter directorist-advanced-filter\">\n    \n                    \n<div class=\"directorist-search-field directorist-form-group directorist-search-query \">\n\n            <label class=\"directorist-search-field__label\" for=\"\">\u00bfQu\u00e9 est\u00e1s buscando?<\/label>\n    \n    <input class=\"directorist-form-element directorist-search-field__input\" id=\"\" type=\"text\" name=\"q\" value=\"\" placeholder=\"\" >\n\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i>    <\/div>\n\n<\/div>                    \n    <div class=\"directorist-search-field directorist-form-group directorist-search-location directorist-icon-right input-has-noLabel\">\n                <span class=\"directorist-input-icon directorist-filter-location-icon\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/crosshairs.svg)\"><\/i><\/span>\n        <input type=\"text\" name=\"address\" id=\"addressId\" value=\"\" placeholder=\"Ubicaci\u00f3n\" autocomplete=\"off\" class=\"directorist-form-element directorist-location-js location-name directorist-search-field__input\" >\n\n        <div class=\"address_result location-names\" style=\"display: none\"><\/div>\n        <input type=\"hidden\" id=\"cityLat\" name=\"cityLat\" value=\"\" \/>\n        <input type=\"hidden\" id=\"cityLng\" name=\"cityLng\" value=\"\" \/>\n\n        <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n        <\/div>\n    <\/div>\n\n                        <div class=\"directorist-search-field directorist-form-group input-has-noLabel\">\n    <div class=\"directorist-select directorist-search-category directorist-search-field__input\">\n\n        \n        <select name=\"in_cat\" class=\"search_fields bdas-category-search directorist-category-select\" data-placeholder=\"Categor\u00eda\"  data-isSearch=\"true\" data-selected-id=\"\" data-selected-label=\"\">\n            <option value=\"\">Select Category<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"30\">Academias<option data-icon=\"\" data-custom-field=\"\" value=\"31\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Clases particulares<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"32\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Idiomas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"33\">Aires acondicionados<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"34\">Alimentaci\u00f3n<option data-icon=\"\" data-custom-field=\"\" value=\"35\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Panader\u00eda \/ Pasteler\u00eda<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"36\">Alquiler<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"37\">Autom\u00f3vil<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"38\">Carpinter\u00edas de aluminio<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"39\">Concesionarios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"40\">Consumibles<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"41\">Coworking<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"42\">Decoraci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"43\">Deportes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"44\">Desinfecci\u00f3n y Seguridad Alimentaria<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"45\">Electricidad e iluminaci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"46\">Electrodom\u00e9sticos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"47\">Er\u00f3tico<option data-icon=\"\" data-custom-field=\"\" value=\"52\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sex shop<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"48\">Estancos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"49\">Est\u00e9tica y bienestar<option data-icon=\"\" data-custom-field=\"\" value=\"50\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Belleza<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"51\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Perfumer\u00edas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"53\">Fabricaci\u00f3n de toldos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"54\">Ferreter\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"55\">Florister\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"56\">Fontaner\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"57\">Fotograf\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"58\">Gasolineras<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"59\">Gimnasios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"60\">Guarder\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"61\">Hogar<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"62\">Imprentas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"63\">Joyer\u00edas y relojer\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"64\">Juguetes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"65\">Limpieza y desinfecci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"66\">Mascotas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"67\">Materiales de construcci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"68\">Moda<option data-icon=\"\" data-custom-field=\"\" value=\"69\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Complementos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"70\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ropa<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"71\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Zapater\u00edas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"72\">Muebles<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"73\">Ocio<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"74\">Papeler\u00edas y librer\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"75\">Pinturas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"76\">Prensa<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"77\">Publicidad<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"78\">Regalos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"79\">Rotulaciones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"80\">R\u00f3tulos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"81\">Salud<option data-icon=\"\" data-custom-field=\"\" value=\"82\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Farmacias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"83\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Herbolarios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"84\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Naturismo<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"85\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Odontolog\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"86\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00d3pticas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"87\">Servicios<option data-icon=\"\" data-custom-field=\"\" value=\"88\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Agencias de viajes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"89\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Alquileres y reparaciones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"90\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Alquileres y reparaciones de maquinarias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"91\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Asesor\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"92\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Despachos profesionales<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"93\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Inmobiliarias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"94\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Seguros<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"95\">Suministros hosteleros<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"96\">Talleres<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"97\">Tecnolog\u00eda<option data-icon=\"\" data-custom-field=\"\" value=\"98\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Inform\u00e1tica<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"99\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Telefon\u00eda<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"100\">Vigilancia y seguridad<\/option>        <\/select>\n\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n<\/div>                \n    <\/div>    <\/div>\n\n    \n<div class=\"directorist-search-form-action\">\n\n    \n    \n        <div class=\"directorist-search-form-action__submit\">\n            <button type=\"submit\" class=\"directorist-btn directorist-btn-lg directorist-btn-primary directorist-btn-search\">\n\n                                    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/search-solid.svg)\"><\/i>                \n                Buscar\n            <\/button>\n        <\/div>\n\n    \n<\/div>\n<\/div>\n\n<div class=\"directorist-search-modal directorist-search-modal--advanced\">\n    \n<div class=\"directorist-search-modal__overlay\"><\/div>\n<div class=\"directorist-search-adv-filter directorist-advanced-filter directorist-search-modal__contents\">\n    <div class=\"directorist-search-modal__contents__header\">\n        <h3 class=\"directorist-search-modal__contents__title\">More Filters<\/h3>\n        <button class=\"directorist-search-modal__contents__btn directorist-search-modal__contents__btn--close\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times.svg)\"><\/i><\/button>\n        <span class=\"directorist-search-modal__minimizer\"><\/span>\n    <\/div>\n    <div class=\"directorist-search-modal__contents__body\">\n                        <div class=\"directorist-advanced-filter__advanced__element directorist-search-field-tag\">\n                    <div class=\"directorist-search-field directorist-search-form-dropdown directorist-form-group \">\n    <div class=\"directorist-search-basic-dropdown directorist-search-field__input\">\n\n                    <label class=\"directorist-search-field__label directorist-search-basic-dropdown-label\">\n                <span class=\"directorist-search-basic-dropdown-selected-prefix\"><\/span>\n                Etiquetas                <span class=\"directorist-search-basic-dropdown-selected-count\"><\/span>\n                <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/chevron-down.svg)\"><\/i> \n            <\/label>\n                <div class=\"directorist-search-basic-dropdown-content\">\n            <div class=\"directorist-search-tags directorist-flex\">\n                \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"740\" id=\"705328568740\" >\n                        <label for=\"705328568740\" class=\"directorist-checkbox__label\">acu\u00e1tico<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"737\" id=\"705328568737\" >\n                        <label for=\"705328568737\" class=\"directorist-checkbox__label\">buceo<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"727\" id=\"705328568727\" >\n                        <label for=\"705328568727\" class=\"directorist-checkbox__label\">doctor computers<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"744\" id=\"705328568744\" >\n                        <label for=\"705328568744\" class=\"directorist-checkbox__label\">gafas<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"749\" id=\"705328568749\" >\n                        <label for=\"705328568749\" class=\"directorist-checkbox__label\">graduaci\u00f3n<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"734\" id=\"705328568734\" >\n                        <label for=\"705328568734\" class=\"directorist-checkbox__label\">hardware<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"732\" id=\"705328568732\" >\n                        <label for=\"705328568732\" class=\"directorist-checkbox__label\">impresoras<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"730\" id=\"705328568730\" >\n                        <label for=\"705328568730\" class=\"directorist-checkbox__label\">inform\u00e1tica<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"748\" id=\"705328568748\" >\n                        <label for=\"705328568748\" class=\"directorist-checkbox__label\">lentes<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"747\" id=\"705328568747\" >\n                        <label for=\"705328568747\" class=\"directorist-checkbox__label\">lentillas<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"741\" id=\"705328568741\" >\n                        <label for=\"705328568741\" class=\"directorist-checkbox__label\">mar<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"733\" id=\"705328568733\" >\n                        <label for=\"705328568733\" class=\"directorist-checkbox__label\">m\u00f3viles<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"742\" id=\"705328568742\" >\n                        <label for=\"705328568742\" class=\"directorist-checkbox__label\">\u00f3ptica<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"743\" id=\"705328568743\" >\n                        <label for=\"705328568743\" class=\"directorist-checkbox__label\">optometr\u00eda<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"728\" id=\"705328568728\" >\n                        <label for=\"705328568728\" class=\"directorist-checkbox__label\">ordenadores<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"738\" id=\"705328568738\" >\n                        <label for=\"705328568738\" class=\"directorist-checkbox__label\">pesca<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"729\" id=\"705328568729\" >\n                        <label for=\"705328568729\" class=\"directorist-checkbox__label\">reparaci\u00f3n<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"735\" id=\"705328568735\" >\n                        <label for=\"705328568735\" class=\"directorist-checkbox__label\">software<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"745\" id=\"705328568745\" >\n                        <label for=\"705328568745\" class=\"directorist-checkbox__label\">sol<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"739\" id=\"705328568739\" >\n                        <label for=\"705328568739\" class=\"directorist-checkbox__label\">submarinismo<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"731\" id=\"705328568731\" >\n                        <label for=\"705328568731\" class=\"directorist-checkbox__label\">t\u00f3ner<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"746\" id=\"705328568746\" >\n                        <label for=\"705328568746\" class=\"directorist-checkbox__label\">vista<\/label>\n                    <\/div>\n\n                                <\/div>\n            <a href=\"#\" class=\"directorist-btn-ml\">Show More<\/a>\n        <\/div>\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n\n<\/div>                <\/div>\n                            <div class=\"directorist-advanced-filter__advanced__element directorist-search-field-radius_search\">\n                    \n<div class=\"directorist-search-field directorist-form-group directorist-search-field-radius_search \">\n            <label class=\"directorist-search-field__label\">Radio (kms)<\/label>\n        <div class=\"directorist-custom-range-slider\">\n        <div class=\"directorist-custom-range-slider__range__wrap\">\n            <span class=\"directorist-custom-range-slider__range__show\"><\/span>\n            <span>Kilometers<\/span>\n        <\/div>\n        <div class=\"directorist-custom-range-slider__slide\" default-value=\"0\" max-value=\"1000\" min-value=\"0\"><\/div>\n        <div class=\"directorist-custom-range-slider__wrap\">\n            <input type=\"hidden\" name=\"radius-search-based-on\" value=\"address\" class=\"directorist-radius_search_based_on\">\n            <input type=\"hidden\" placeholder=\"Min\" value=\"0\" class=\"directorist-custom-range-slider__radius directorist-custom-range-slider__value__min\">\n            <input type=\"hidden\" placeholder=\"Max\" value=\"1000\" class=\"directorist-custom-range-slider__radius directorist-custom-range-slider__value__max\">\n            <input type=\"hidden\" name=\"miles\" class=\"directorist-custom-range-slider__range\" value=\"0-1000\">\n        <\/div>\n    <\/div>\n\n<\/div>                <\/div>\n                <\/div>\n    <div class=\"directorist-search-modal__contents__footer\">\n            <\/div>\n<\/div>\n<\/div>\n            <\/div>\n\n        <\/form>\n\n        \n        \n    <\/div>\n\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0326b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fb0326b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63fff08 e-flex e-con-boxed e-con e-parent\" data-id=\"63fff08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b59110 e-con-full e-flex e-con e-child\" data-id=\"5b59110\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4de788b elementor-widget elementor-widget-text-editor\" data-id=\"4de788b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\">Somos el coraz\u00f3n de Torrevieja<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86a9971 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"86a9971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee3483 elementor-widget elementor-widget-text-editor\" data-id=\"4ee3483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>APYMECO<\/strong>\u00a0somos la asociaci\u00f3n de comerciantes de Torrevieja. Trabajamos para conseguir un comercio\u00a0<strong>justo y transparente<\/strong>, tanto para nuestros\u00a0<strong>asociados<\/strong>\u00a0como para nuestros\u00a0<strong>clientes<\/strong>.<\/p><p>Somos el\u00a0<strong>coraz\u00f3n<\/strong>\u00a0de nuestra ciudad y queremos que lata con fuerza, por eso ponemos a tu disposici\u00f3n un novedoso sistema de\u00a0<strong>directorios<\/strong>\u00a0para que conozcas\u00a0<strong>toda la oferta<\/strong>\u00a0de comercio de nuestros asociados en Torrevieja.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de118b elementor-widget elementor-widget-heading\" data-id=\"1de118b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00daltimas noticias<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93f2882 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"93f2882\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652286d elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"652286d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;2&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8389 post type-post status-publish format-standard has-post-thumbnail hentry category-eventos category-junta-directiva category-premios category-reconocimientos tag-premios-apymeco-26 tag-torrevieja-weekend-26\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/apymeco.netrotec.com\/en\/gala-del-comercio-en-torrevieja-weekend-2026\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/Diseno-sin-titulo-1-300x111.png\" class=\"attachment-medium size-medium wp-image-8402\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/Diseno-sin-titulo-1-300x111.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/Diseno-sin-titulo-1-768x284.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/Diseno-sin-titulo-1-18x7.png 18w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/Diseno-sin-titulo-1.png 851w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/apymeco.netrotec.com\/en\/gala-del-comercio-en-torrevieja-weekend-2026\/\" >\n\t\t\t\tGala del Comercio en Torrevieja Weekend 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/06\/2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En el marco de la 5ta edici\u00f3n del desfile \u201cTorrevieja Weekend\u201d celebrado el pasado s\u00e1bado 6 de junio, desde la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/apymeco.netrotec.com\/en\/gala-del-comercio-en-torrevieja-weekend-2026\/\" aria-label=\"Read more about Gala del Comercio en Torrevieja Weekend 2026\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8373 post type-post status-publish format-standard has-post-thumbnail hentry category-bases-de-concursos category-campanas category-sorteos tag-apymeco-campanas tag-comercio-local-apymeco tag-comprar-en-torrevieja tag-dia-de-la-madre-torrevieja tag-ofertas-dia-de-la-madre tag-promociones-comercio-local tag-ruleta-del-comercio-apymeco tag-torrevieja\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-lanza-la-ruleta-del-comercio-para-el-dia-de-la-madre\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"161\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE-300x161.png\" class=\"attachment-medium size-medium wp-image-8377\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE-300x161.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE-1024x551.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE-768x413.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE-18x10.png 18w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/04\/CHEQUE-RULETA-MADRE.png 1517w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-lanza-la-ruleta-del-comercio-para-el-dia-de-la-madre\/\" >\n\t\t\t\tAPYMECO lanza la \u201cRuleta del Comercio\u201d para el D\u00eda de la Madre\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25\/04\/2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En APYMECO celebramos el D\u00eda de la Madre impulsando el comercio local con una campa\u00f1a que combina compras, premios y<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-lanza-la-ruleta-del-comercio-para-el-dia-de-la-madre\/\" aria-label=\"Read more about APYMECO lanza la \u201cRuleta del Comercio\u201d para el D\u00eda de la Madre\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8356 post type-post status-publish format-standard has-post-thumbnail hentry category-informacion category-notas-de-prensa\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-y-banco-sabadell-firman-un-acuerdo-para-impulsar-el-comercio-local-de-torrevieja\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok-229x300.jpeg\" class=\"attachment-medium size-medium wp-image-8358\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok-229x300.jpeg 229w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok-783x1024.jpeg 783w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok-768x1005.jpeg 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok-9x12.jpeg 9w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/03\/convenio-4-marzo-26-ok.jpeg 1041w\" sizes=\"(max-width: 229px) 100vw, 229px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-y-banco-sabadell-firman-un-acuerdo-para-impulsar-el-comercio-local-de-torrevieja\/\" >\n\t\t\t\tAPYMECO y Banco Sabadell  firman un acuerdo para impulsar el comercio local de Torrevieja\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t05\/03\/2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Torrevieja, 5 de marzo de 2026 &nbsp; La Asociaci\u00f3n de Peque\u00f1os y Medianos Comerciantes de Torrevieja (APYMECO) y Banco Sabadell<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/apymeco.netrotec.com\/en\/apymeco-y-banco-sabadell-firman-un-acuerdo-para-impulsar-el-comercio-local-de-torrevieja\/\" aria-label=\"Read more about APYMECO y Banco Sabadell  firman un acuerdo para impulsar el comercio local de Torrevieja\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8326 post type-post status-publish format-standard has-post-thumbnail hentry category-informacion tag-afecancer-torrevieja tag-apymeco-postales-solidarias tag-postales-solidarias\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/apymeco.netrotec.com\/en\/arte-y-solidaridad\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-300x169.png\" class=\"attachment-medium size-medium wp-image-8332\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-300x169.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-1024x576.png 1024w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-768x432.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-1536x864.png 1536w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-18x10.png 18w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2-640x360.png 640w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/02\/titulo-2.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/apymeco.netrotec.com\/en\/arte-y-solidaridad\/\" >\n\t\t\t\tBrotes de una nueva vida: arte y solidaridad torrevejense para AFEC\u00c1NCER\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t20\/02\/2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Los torrevejenses Ana Cutillas y Eduardo Aranda Hortelano han impulsado la campa\u00f1a solidaria \u201cBrotes de una nueva vida\u201d, una iniciativa<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/apymeco.netrotec.com\/en\/arte-y-solidaridad\/\" aria-label=\"Read more about Brotes de una nueva vida: arte y solidaridad torrevejense para AFEC\u00c1NCER\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-759b319 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"759b319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64781ed elementor-widget elementor-widget-heading\" data-id=\"64781ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">COMPRA EN TU CIUDAD, COMPRA CON CONFIANZA<\/h4>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8c6e9e e-con-full e-flex e-con e-child\" data-id=\"d8c6e9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4b25ba4 e-con-full e-flex e-con e-child\" data-id=\"4b25ba4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5e6bd8 elementor-widget elementor-widget-text-editor\" data-id=\"b5e6bd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4>\u00a0<\/h4><p>Sabemos lo importante que eres y por eso abrimos las puertas de\u00a0<strong>nuestras<\/strong>\u00a0casas para que te sientas como en\u00a0<strong>la tuya<\/strong>. Comprar en tu ciudad es comprar a\u00a0<strong>tu vecino<\/strong>, a la gente que conoces y te conoce. Esa transparencia es garant\u00eda de\u00a0<strong>confianza.\u00a0<\/strong><\/p><p>Estar en tu barrio y relacionarnos con frecuencia nos ayuda a\u00a0<strong>conocerte mejor<\/strong>\u00a0y poder ofrecerte un\u00a0<strong>trato personalizado<\/strong> \u00fanico.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61ea3e1 e-con-full e-flex e-con e-child\" data-id=\"61ea3e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6414085 elementor-widget elementor-widget-image\" data-id=\"6414085\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"442\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/1_uYfVGhAYq6ss6n_wBrRvBw-1024x697-2-2776476228.jpeg\" class=\"attachment-full size-full wp-image-8706\" alt=\"\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/1_uYfVGhAYq6ss6n_wBrRvBw-1024x697-2-2776476228.jpeg 650w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/1_uYfVGhAYq6ss6n_wBrRvBw-1024x697-2-2776476228-300x204.jpeg 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/1_uYfVGhAYq6ss6n_wBrRvBw-1024x697-2-2776476228-18x12.jpeg 18w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<p class=\"e-9a8ccac-0cfbd51 e-paragraph-base\" data-interaction-id=\"9a8ccac\">Porque queremos que cada vez que compres lo hagas con&nbsp;<strong>seguridad<\/strong>&nbsp;y&nbsp;<strong>confianza<\/strong>.&nbsp;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac6809b e-con-full e-flex e-con e-child\" data-id=\"ac6809b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b6871ed e-con e-atomic-element e-div-block-base e-b6871ed-3624270 \" data-id=\"b6871ed\" data-element_type=\"e-div-block\" data-e-type=\"e-div-block\" data-interaction-id=\"b6871ed\">\n    \t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base \" data-interaction-id=\"694eaa3\" id=\"8655\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/banco-sabadell-768x173-1.png\" width=\"768\" height=\"173\" srcset=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/banco-sabadell-768x173-1.png 768w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/banco-sabadell-768x173-1-300x68.png 300w, https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/banco-sabadell-768x173-1-18x4.png 18w\" alt=\"\"\/>\t\t\t\t<div class=\"elementor-element elementor-element-643ac46 elementor-widget elementor-widget-text-editor\" data-id=\"643ac46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4>PROMO BANCO SABADELL PARA ASOCIADOS<\/h4><h5>Te abonamos tu cuota de asociado hasta un m\u00e1ximo de 100 euros<\/h5><p>Si eres miembro de la Asociaci\u00f3n de Peque\u00f1os y Medianos Comerciantes de Torrevieja (APYMECO) te abonamos tu cuota de colegiado o asociado, con un m\u00e1ximo de 100 euros por cuenta.<\/p><p>La bonificaci\u00f3n se realizar\u00e1 un \u00fanico a\u00f1o para cuotas domiciliadas durante los 12 primeros meses, contando como primer mes el de la apertura de la cuenta. El pago se realizar\u00e1 en cuenta el mes siguiente de los 12 primeros meses. El incentivo estar\u00e1 sujeto a la retenci\u00f3n fiscal vigente.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d33a57 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3d33a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sab.to\/351509-es\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quiero esta oferta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t<div class=\"elementor-element elementor-element-202d946 elementor-widget elementor-widget-heading\" data-id=\"202d946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00daltimos asociados<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d266121 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d266121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86b5979 elementor-widget elementor-widget-directorist_all_listing\" data-id=\"86b5979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"directorist_all_listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- directorist-shortcode:: [ directorist_all_listing] -->\n<div class=\"directorist-archive-contents directorist-contents-wrap directorist-w-100 directorist-instant-search\"data-atts=\"{&quot;header&quot;:&quot;&quot;,&quot;header_title&quot;:&quot;Listings Found&quot;,&quot;advanced_filter&quot;:&quot;no&quot;,&quot;view&quot;:&quot;list&quot;,&quot;map_height&quot;:500,&quot;columns&quot;:&quot;2&quot;,&quot;listings_per_page&quot;:4,&quot;show_pagination&quot;:&quot;no&quot;,&quot;category&quot;:&quot;&quot;,&quot;tag&quot;:&quot;&quot;,&quot;location&quot;:&quot;&quot;,&quot;featured_only&quot;:&quot;no&quot;,&quot;popular_only&quot;:&quot;no&quot;,&quot;logged_in_user_only&quot;:&quot;no&quot;,&quot;display_preview_image&quot;:&quot;yes&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;sidebar&quot;:&quot;no_sidebar&quot;,&quot;_current_page&quot;:&quot;listing&quot;}\">\n    <div class=\"directorist-archive-contents__top\">\n        \n        \n<div class=\"directorist-search-modal directorist-search-modal--full\">\n    <div class=\"directorist-search-modal__overlay\"><\/div>\n    <div class=\"directorist-search-modal__contents directorist-archive-adv-filter directorist-advanced-filter\">\n        <form action=\"https:\/\/apymeco.netrotec.com\/en\/resultados-de-la-busqueda-2\/\" class=\"directorist-advanced-filter__form\">\n            <div class=\"directorist-search-modal__contents__header\">\n                <h3 class=\"directorist-search-modal__contents__title\">More Filters<\/h3>\n                <button class=\"directorist-search-modal__contents__btn directorist-search-modal__contents__btn--close\">\n                    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times.svg)\"><\/i>                <\/button>\n                <span class=\"directorist-search-modal__minimizer\"><\/span>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__body\">\n                <input type=\"hidden\" name='directory_type' value='business'>\n                <div class=\"directorist-advanced-filter__basic\">\n                                            <div class=\"directorist-advanced-filter__basic__element\">\n<div class=\"directorist-search-field directorist-form-group directorist-search-query \">\n\n            <label class=\"directorist-search-field__label\" for=\"\">\u00bfQu\u00e9 est\u00e1s buscando?<\/label>\n    \n    <input class=\"directorist-form-element directorist-search-field__input\" id=\"\" type=\"text\" name=\"q\" value=\"\" placeholder=\"\" >\n\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i>    <\/div>\n\n<\/div><\/div>\n                                            <div class=\"directorist-advanced-filter__basic__element\">\n    <div class=\"directorist-search-field directorist-form-group directorist-search-location directorist-icon-right input-has-noLabel\">\n                <span class=\"directorist-input-icon directorist-filter-location-icon\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/crosshairs.svg)\"><\/i><\/span>\n        <input type=\"text\" name=\"address\" id=\"addressId\" value=\"\" placeholder=\"Ubicaci\u00f3n\" autocomplete=\"off\" class=\"directorist-form-element directorist-location-js location-name directorist-search-field__input\" >\n\n        <div class=\"address_result location-names\" style=\"display: none\"><\/div>\n        <input type=\"hidden\" id=\"cityLat\" name=\"cityLat\" value=\"\" \/>\n        <input type=\"hidden\" id=\"cityLng\" name=\"cityLng\" value=\"\" \/>\n\n        <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n        <\/div>\n    <\/div>\n\n    <\/div>\n                                            <div class=\"directorist-advanced-filter__basic__element\"><div class=\"directorist-search-field directorist-form-group input-has-noLabel\">\n    <div class=\"directorist-select directorist-search-category directorist-search-field__input\">\n\n        \n        <select name=\"in_cat\" class=\"directory_field bdas-category-search directorist-category-select\" data-placeholder=\"Categor\u00eda\"  data-isSearch=\"true\" data-selected-id=\"\" data-selected-label=\"\">\n            <option value=\"\">Select Category<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"30\">Academias<option data-icon=\"\" data-custom-field=\"\" value=\"31\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Clases particulares<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"32\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Idiomas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"33\">Aires acondicionados<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"34\">Alimentaci\u00f3n<option data-icon=\"\" data-custom-field=\"\" value=\"35\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Panader\u00eda \/ Pasteler\u00eda<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"36\">Alquiler<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"37\">Autom\u00f3vil<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"38\">Carpinter\u00edas de aluminio<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"39\">Concesionarios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"40\">Consumibles<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"41\">Coworking<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"42\">Decoraci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"43\">Deportes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"44\">Desinfecci\u00f3n y Seguridad Alimentaria<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"45\">Electricidad e iluminaci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"46\">Electrodom\u00e9sticos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"47\">Er\u00f3tico<option data-icon=\"\" data-custom-field=\"\" value=\"52\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sex shop<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"48\">Estancos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"49\">Est\u00e9tica y bienestar<option data-icon=\"\" data-custom-field=\"\" value=\"50\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Belleza<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"51\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Perfumer\u00edas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"53\">Fabricaci\u00f3n de toldos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"54\">Ferreter\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"55\">Florister\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"56\">Fontaner\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"57\">Fotograf\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"58\">Gasolineras<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"59\">Gimnasios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"60\">Guarder\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"61\">Hogar<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"62\">Imprentas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"63\">Joyer\u00edas y relojer\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"64\">Juguetes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"65\">Limpieza y desinfecci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"66\">Mascotas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"67\">Materiales de construcci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"68\">Moda<option data-icon=\"\" data-custom-field=\"\" value=\"69\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Complementos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"70\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ropa<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"71\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Zapater\u00edas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"72\">Muebles<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"73\">Ocio<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"74\">Papeler\u00edas y librer\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"75\">Pinturas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"76\">Prensa<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"77\">Publicidad<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"78\">Regalos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"79\">Rotulaciones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"80\">R\u00f3tulos<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"81\">Salud<option data-icon=\"\" data-custom-field=\"\" value=\"82\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Farmacias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"83\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Herbolarios<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"84\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Naturismo<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"85\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Odontolog\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"86\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00d3pticas<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"87\">Servicios<option data-icon=\"\" data-custom-field=\"\" value=\"88\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Agencias de viajes<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"89\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Alquileres y reparaciones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"90\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Alquileres y reparaciones de maquinarias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"91\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Asesor\u00edas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"92\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Despachos profesionales<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"93\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Inmobiliarias<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"94\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Seguros<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"95\">Suministros hosteleros<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"96\">Talleres<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"97\">Tecnolog\u00eda<option data-icon=\"\" data-custom-field=\"\" value=\"98\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Inform\u00e1tica<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"99\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Telefon\u00eda<\/option><\/option><option data-icon=\"\" data-custom-field=\"\" value=\"100\">Vigilancia y seguridad<\/option>        <\/select>\n\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n<\/div><\/div>\n                                    <\/div>\n\n                <div class=\"directorist-advanced-filter__advanced\">\n                                            <div class=\"directorist-advanced-filter__advanced__element directorist-search-field-tag\"><div class=\"directorist-search-field directorist-search-form-dropdown directorist-form-group \">\n    <div class=\"directorist-search-basic-dropdown directorist-search-field__input\">\n\n                    <label class=\"directorist-search-field__label directorist-search-basic-dropdown-label\">\n                <span class=\"directorist-search-basic-dropdown-selected-prefix\"><\/span>\n                Etiquetas                <span class=\"directorist-search-basic-dropdown-selected-count\"><\/span>\n                <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/chevron-down.svg)\"><\/i> \n            <\/label>\n                <div class=\"directorist-search-basic-dropdown-content\">\n            <div class=\"directorist-search-tags directorist-flex\">\n                \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"740\" id=\"518778631740\" >\n                        <label for=\"518778631740\" class=\"directorist-checkbox__label\">acu\u00e1tico<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"737\" id=\"518778631737\" >\n                        <label for=\"518778631737\" class=\"directorist-checkbox__label\">buceo<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"727\" id=\"518778631727\" >\n                        <label for=\"518778631727\" class=\"directorist-checkbox__label\">doctor computers<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"744\" id=\"518778631744\" >\n                        <label for=\"518778631744\" class=\"directorist-checkbox__label\">gafas<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"749\" id=\"518778631749\" >\n                        <label for=\"518778631749\" class=\"directorist-checkbox__label\">graduaci\u00f3n<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"734\" id=\"518778631734\" >\n                        <label for=\"518778631734\" class=\"directorist-checkbox__label\">hardware<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"732\" id=\"518778631732\" >\n                        <label for=\"518778631732\" class=\"directorist-checkbox__label\">impresoras<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"730\" id=\"518778631730\" >\n                        <label for=\"518778631730\" class=\"directorist-checkbox__label\">inform\u00e1tica<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"748\" id=\"518778631748\" >\n                        <label for=\"518778631748\" class=\"directorist-checkbox__label\">lentes<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"747\" id=\"518778631747\" >\n                        <label for=\"518778631747\" class=\"directorist-checkbox__label\">lentillas<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"741\" id=\"518778631741\" >\n                        <label for=\"518778631741\" class=\"directorist-checkbox__label\">mar<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"733\" id=\"518778631733\" >\n                        <label for=\"518778631733\" class=\"directorist-checkbox__label\">m\u00f3viles<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"742\" id=\"518778631742\" >\n                        <label for=\"518778631742\" class=\"directorist-checkbox__label\">\u00f3ptica<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"743\" id=\"518778631743\" >\n                        <label for=\"518778631743\" class=\"directorist-checkbox__label\">optometr\u00eda<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"728\" id=\"518778631728\" >\n                        <label for=\"518778631728\" class=\"directorist-checkbox__label\">ordenadores<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"738\" id=\"518778631738\" >\n                        <label for=\"518778631738\" class=\"directorist-checkbox__label\">pesca<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"729\" id=\"518778631729\" >\n                        <label for=\"518778631729\" class=\"directorist-checkbox__label\">reparaci\u00f3n<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"735\" id=\"518778631735\" >\n                        <label for=\"518778631735\" class=\"directorist-checkbox__label\">software<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"745\" id=\"518778631745\" >\n                        <label for=\"518778631745\" class=\"directorist-checkbox__label\">sol<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"739\" id=\"518778631739\" >\n                        <label for=\"518778631739\" class=\"directorist-checkbox__label\">submarinismo<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"731\" id=\"518778631731\" >\n                        <label for=\"518778631731\" class=\"directorist-checkbox__label\">t\u00f3ner<\/label>\n                    <\/div>\n\n                    \n                    <div class=\"directorist-checkbox directorist-checkbox-primary\">\n                        <input type=\"checkbox\" name=\"in_tag[]\" value=\"746\" id=\"518778631746\" >\n                        <label for=\"518778631746\" class=\"directorist-checkbox__label\">vista<\/label>\n                    <\/div>\n\n                                <\/div>\n            <a href=\"#\" class=\"directorist-btn-ml\">Show More<\/a>\n        <\/div>\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n\n<\/div><\/div>\n                                            <div class=\"directorist-advanced-filter__advanced__element directorist-search-field-radius_search\">\n<div class=\"directorist-search-field directorist-form-group directorist-search-field-radius_search \">\n            <label class=\"directorist-search-field__label\">Radio (kms)<\/label>\n        <div class=\"directorist-custom-range-slider\">\n        <div class=\"directorist-custom-range-slider__range__wrap\">\n            <span class=\"directorist-custom-range-slider__range__show\"><\/span>\n            <span>Kilometers<\/span>\n        <\/div>\n        <div class=\"directorist-custom-range-slider__slide\" default-value=\"0\" max-value=\"1000\" min-value=\"0\"><\/div>\n        <div class=\"directorist-custom-range-slider__wrap\">\n            <input type=\"hidden\" name=\"radius-search-based-on\" value=\"address\" class=\"directorist-radius_search_based_on\">\n            <input type=\"hidden\" placeholder=\"Min\" value=\"0\" class=\"directorist-custom-range-slider__radius directorist-custom-range-slider__value__min\">\n            <input type=\"hidden\" placeholder=\"Max\" value=\"1000\" class=\"directorist-custom-range-slider__radius directorist-custom-range-slider__value__max\">\n            <input type=\"hidden\" name=\"miles\" class=\"directorist-custom-range-slider__range\" value=\"0-1000\">\n        <\/div>\n    <\/div>\n\n<\/div><\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__footer\">\n                \n<div class=\"directorist-advanced-filter__action directorist-flex directorist-align-center directorist-justify-content-between flex-wrap\">\n\n            <button type=\"submit\" class=\"directorist-btn directorist-btn-sm directorist-btn-submit\">Aplicar filtros<\/button>\n    \n            <button type=\"submit\" class=\"directorist-btn-reset-js\">Restablecer filtros<\/button>\n    \n<\/div>            <\/div>\n        <\/form>\n    <\/div>\n<\/div>    <\/div>\n    <div class=\"directorist-archive-contents__listings\">\n        \n<div class=\"directorist-archive-items directorist-archive-list-view \">\n    <div class=\"directorist-container-fluid\">\n\n        \n            \n                <div class=\"directorist-row\">\n                                <div class=\"directorist-col-12\">\n            \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-list directorist-listing-has-thumb \">\n\n    <div class=\"directorist-listing-single__thumb\">\n        <div class=\"directorist-thumnail-card directorist-card-cover\" style=\"height: 260px\"><div class=\"directorist-thumnail-card-front-wrap\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/la-tienda-de-david\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/07\/LA-TIENDA-DE-DAVID-1258470181-640x278.jpg\" alt=\"LA-TIENDA-DE-DAVID-1258470181\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><\/div>        <div class=\"directorist-thumb-top-right\"><\/div>\n    <\/div>\n\n    <section class=\"directorist-listing-single__content\">\n\n        <div class=\"directorist-listing-single__info\">\n            \n            \n            <div class=\"directorist-listing-single__info__top-right\">\n                <header class=\"directorist-listing-single__info__top\">\n                    \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/la-tienda-de-david\/\">LA TIENDA DE DAVID<\/a><\/h2>\n\n                <\/header>\n                <div class=\"directorist-listing-single__info__right\">\n                    <div class=\"directorist-listing-single__action\">\n                                            <\/div>\n                <\/div>\n            <\/div>\n            \n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-location\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/map-marker-solid.svg)\"><\/i>        <div class=\"directorist-listing-card-location-list\">\n        <a href=\"https:\/\/apymeco.netrotec.com\/en\/ubicacion-unica\/torrevieja\/?directory_type=business\" rel=\"tag\">Torrevieja<\/a>    <\/div>\n<\/li>\n<li class=\"directorist-listing-card-posted-on\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/clock-solid.svg)\"><\/i>    <span>\n        17\/07\/2026    <\/span>\n<\/li>            <\/ul>\n\n            \n            \n            \n                    <\/div>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/footer>\n\n    <\/section>\n    <footer class=\"directorist-listing-single__mobile-view-meta\">\n        <div class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/div>\n    <\/footer>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-12\">\n            \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-list directorist-listing-has-thumb \">\n\n    <div class=\"directorist-listing-single__thumb\">\n        <div class=\"directorist-thumnail-card directorist-card-cover\" style=\"height: 260px\"><div class=\"directorist-thumnail-card-front-wrap\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/carniceria-juan-diego\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/07\/juan-diego-fachada-1085660295-640x360.jpg\" alt=\"juan-diego-fachada-1085660295\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><\/div>        <div class=\"directorist-thumb-top-right\"><\/div>\n    <\/div>\n\n    <section class=\"directorist-listing-single__content\">\n\n        <div class=\"directorist-listing-single__info\">\n            \n            \n            <div class=\"directorist-listing-single__info__top-right\">\n                <header class=\"directorist-listing-single__info__top\">\n                    \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/carniceria-juan-diego\/\">CARNICERIA JUAN DIEGO<\/a><\/h2>\n\n                <\/header>\n                <div class=\"directorist-listing-single__info__right\">\n                    <div class=\"directorist-listing-single__action\">\n                                            <\/div>\n                <\/div>\n            <\/div>\n            \n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-location\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/map-marker-solid.svg)\"><\/i>        <div class=\"directorist-listing-card-location-list\">\n        <a href=\"https:\/\/apymeco.netrotec.com\/en\/ubicacion-unica\/torrevieja\/?directory_type=business\" rel=\"tag\">Torrevieja<\/a>    <\/div>\n<\/li>\n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:966704810\">\n        966 704 810    <\/a>\n<\/li>\n\n<li class=\"directorist-listing-card-posted-on\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/clock-solid.svg)\"><\/i>    <span>\n        17\/07\/2026    <\/span>\n<\/li>            <\/ul>\n\n            \n            \n            \n                    <\/div>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/footer>\n\n    <\/section>\n    <footer class=\"directorist-listing-single__mobile-view-meta\">\n        <div class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/div>\n    <\/footer>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-12\">\n            \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-list directorist-listing-has-thumb \">\n\n    <div class=\"directorist-listing-single__thumb\">\n        <div class=\"directorist-thumnail-card directorist-card-cover\" style=\"height: 260px\"><div class=\"directorist-thumnail-card-front-wrap\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/andres-gourmet-seleccion\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/07\/andres-gourmet-640x360.jpg\" alt=\"andres-gourmet\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><\/div>        <div class=\"directorist-thumb-top-right\"><\/div>\n    <\/div>\n\n    <section class=\"directorist-listing-single__content\">\n\n        <div class=\"directorist-listing-single__info\">\n            \n            \n            <div class=\"directorist-listing-single__info__top-right\">\n                <header class=\"directorist-listing-single__info__top\">\n                    \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/andres-gourmet-seleccion\/\">ANDRES GOURMET SELECCI\u00d3N<\/a><\/h2>\n\n                <\/header>\n                <div class=\"directorist-listing-single__info__right\">\n                    <div class=\"directorist-listing-single__action\">\n                                            <\/div>\n                <\/div>\n            <\/div>\n            \n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-location\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/map-marker-solid.svg)\"><\/i>        <div class=\"directorist-listing-card-location-list\">\n        <a href=\"https:\/\/apymeco.netrotec.com\/en\/ubicacion-unica\/torrevieja\/?directory_type=business\" rel=\"tag\">Torrevieja<\/a>    <\/div>\n<\/li>\n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:966928863\">\n        966 928 863    <\/a>\n<\/li>\n\n<li class=\"directorist-listing-card-posted-on\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/clock-solid.svg)\"><\/i>    <span>\n        17\/07\/2026    <\/span>\n<\/li>            <\/ul>\n\n            \n            \n            \n                    <\/div>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/footer>\n\n    <\/section>\n    <footer class=\"directorist-listing-single__mobile-view-meta\">\n        <div class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/alimentacion\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Alimentaci\u00f3n<\/a>\n        <\/div>\n<\/div>\n        <\/div>\n    <\/footer>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-12\">\n            \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-list directorist-listing-has-thumb \">\n\n    <div class=\"directorist-listing-single__thumb\">\n        <div class=\"directorist-thumnail-card directorist-card-cover\" style=\"height: 260px\"><div class=\"directorist-thumnail-card-front-wrap\"><div class=\"directorist-swiper directorist-swiper-listing\" data-sw-items=\"1\" data-sw-margin=\"2\" data-sw-loop=\"true\" data-sw-perslide=\"1\" data-sw-speed=\"500\" data-sw-autoplay=\"false\" data-sw-responsive=\"{}\">\n\t\t\t\t\t<div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/OdiseaDiving-1273376609-640x297.jpg\" alt=\"OdiseaDiving-1273376609\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/unnamed-1-2-640x360.webp\" alt=\"unnamed (1)\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/unnamed-2-2-640x360.webp\" alt=\"unnamed (2)\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/unnamed-3-2-640x360.webp\" alt=\"unnamed (3)\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\"><figure><img decoding=\"async\" src=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/unnamed-6-640x360.webp\" alt=\"unnamed\" class=\"directorist-thumnail-card-front-img\" \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class=\"directorist-swiper__navigation\">\n\t\t\t\t\t\t<div class=\"directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class=\"directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"directorist-swiper__pagination directorist-swiper__pagination--listing\"><\/div>\n\t\t\t\t<\/div><\/div><\/div>        <div class=\"directorist-thumb-top-right\"><\/div>\n    <\/div>\n\n    <section class=\"directorist-listing-single__content\">\n\n        <div class=\"directorist-listing-single__info\">\n            \n            \n            <div class=\"directorist-listing-single__info__top-right\">\n                <header class=\"directorist-listing-single__info__top\">\n                    \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/apymeco.netrotec.com\/en\/asociados\/odisea-diving\/\">Odisea Diving<\/a><\/h2>\n\n                <\/header>\n                <div class=\"directorist-listing-single__info__right\">\n                    <div class=\"directorist-listing-single__action\">\n                                            <\/div>\n                <\/div>\n            <\/div>\n            \n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-location\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/map-marker-solid.svg)\"><\/i>        <div class=\"directorist-listing-card-location-list\">\n        <a href=\"https:\/\/apymeco.netrotec.com\/en\/ubicacion-unica\/torrevieja\/?directory_type=business\" rel=\"tag\">Torrevieja<\/a>    <\/div>\n<\/li>\n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:966704901\">\n        966704901    <\/a>\n<\/li>\n\n<li class=\"directorist-listing-card-posted-on\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/clock-solid.svg)\"><\/i>    <span>\n        23\/06\/2026    <\/span>\n<\/li>            <\/ul>\n\n            \n            \n            \n                    <\/div>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/deportes\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Deportes<\/a>\n        <\/div>\n<\/div>\n        <\/footer>\n\n    <\/section>\n    <footer class=\"directorist-listing-single__mobile-view-meta\">\n        <div class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\"><\/div>\n            <div class=\"directorist-listing-single__meta__right\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/apymeco.netrotec.com\/en\/categoria-unica\/deportes\/?directory_type=business\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/apymeco.netrotec.com\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/regular\/folder.svg)\"><\/i>Deportes<\/a>\n        <\/div>\n<\/div>\n        <\/div>\n    <\/footer>\n\n<\/article>            <\/div>\n                                <\/div>\n                <div\/>\n                \n                \n                \n                <\/div>\n<\/div>    <\/div>\n\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>APYMECO TORREVIEJA +30 A\u00d1OS elevando nuestro comercio a lo m\u00e1s alto Buscar establecimientos \u00a1Todo lo que necesitas, en tu comercio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Inicio - APYMECO Torrevieja<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apymeco.netrotec.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicio\" \/>\n<meta property=\"og:description\" content=\"APYMECO TORREVIEJA +30 A\u00d1OS elevando nuestro comercio a lo m\u00e1s alto Buscar establecimientos \u00a1Todo lo que necesitas, en tu comercio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apymeco.netrotec.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"APYMECO Torrevieja\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T07:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"name\":\"Inicio - APYMECO Torrevieja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/layerslider\\\/projects\\\/Sky-Experience\\\/sky.png\",\"datePublished\":\"2026-06-02T07:11:34+00:00\",\"dateModified\":\"2026-06-23T07:22:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apymeco.netrotec.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/layerslider\\\/projects\\\/Sky-Experience\\\/sky.png\",\"contentUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/layerslider\\\/projects\\\/Sky-Experience\\\/sky.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#website\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"name\":\"APYMECO Torrevieja\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apymeco.netrotec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#organization\",\"name\":\"APYMECO Torrevieja\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-blanco.png\",\"contentUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-blanco.png\",\"width\":1107,\"height\":444,\"caption\":\"APYMECO Torrevieja\"},\"image\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inicio - APYMECO Torrevieja","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apymeco.netrotec.com\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Inicio","og_description":"APYMECO TORREVIEJA +30 A\u00d1OS elevando nuestro comercio a lo m\u00e1s alto Buscar establecimientos \u00a1Todo lo que necesitas, en tu comercio [&hellip;]","og_url":"https:\/\/apymeco.netrotec.com\/en\/","og_site_name":"APYMECO Torrevieja","article_modified_time":"2026-06-23T07:22:27+00:00","og_image":[{"url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apymeco.netrotec.com\/","url":"https:\/\/apymeco.netrotec.com\/","name":"Inicio - APYMECO Torrevieja","isPartOf":{"@id":"https:\/\/apymeco.netrotec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apymeco.netrotec.com\/#primaryimage"},"image":{"@id":"https:\/\/apymeco.netrotec.com\/#primaryimage"},"thumbnailUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png","datePublished":"2026-06-02T07:11:34+00:00","dateModified":"2026-06-23T07:22:27+00:00","breadcrumb":{"@id":"https:\/\/apymeco.netrotec.com\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apymeco.netrotec.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/apymeco.netrotec.com\/#primaryimage","url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png","contentUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/layerslider\/projects\/Sky-Experience\/sky.png"},{"@type":"BreadcrumbList","@id":"https:\/\/apymeco.netrotec.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apymeco.netrotec.com\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/apymeco.netrotec.com\/#website","url":"https:\/\/apymeco.netrotec.com\/","name":"APYMECO Torrevieja","description":"","publisher":{"@id":"https:\/\/apymeco.netrotec.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apymeco.netrotec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/apymeco.netrotec.com\/#organization","name":"APYMECO Torrevieja","url":"https:\/\/apymeco.netrotec.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/logo\/image\/","url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/logo-blanco.png","contentUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/logo-blanco.png","width":1107,"height":444,"caption":"APYMECO Torrevieja"},"image":{"@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":79,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":8744,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/8744"}],"wp:attachment":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}