{"id":5729,"date":"2020-02-19T18:27:00","date_gmt":"2020-02-19T17:27:00","guid":{"rendered":"https:\/\/www.apymeco.info\/?p=5729"},"modified":"2020-02-19T18:27:00","modified_gmt":"2020-02-19T17:27:00","slug":"el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco","status":"publish","type":"post","link":"https:\/\/apymeco.netrotec.com\/en\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/","title":{"rendered":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco."},"content":{"rendered":"<p>El alcalde de Torrevieja, Eduardo Dol\u00f3n, recibi\u00f3 ayer a la nueva Junta Directiva de la Asociaci\u00f3n de Peque\u00f1os y Medianos Comerciantes (Apymeco), proclamada hace unos d\u00edas y que preside Jorge Almarcha. A esta primera toma de contacto con el Ayuntamiento de Torrevieja asistieron tambi\u00e9n la concejal de Comercio y Hosteler\u00eda, Rosario Mart\u00ednez Chaza<span class=\"text_exposed_show\">rra; el asesor y coordinador de Comercio, Jos\u00e9 Rubio; el vicepresidente de la asociaci\u00f3n, Pedro Andr\u00e9s Garc\u00eda; el secretario, Fernando Guardiola; el tesorero, Luis Ismael Canto y la vocal de extranjeros, Nicoletta Predassi. <\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>La nueva Directiva expuso al alcalde la situaci\u00f3n en la que han encontrado la Asociaci\u00f3n, exponiendo la preocupaci\u00f3n por ilusionar a la masa social de la entidad con nuevos proyectos. Para ello, presentaron una serie de actuaciones para este ejercicio, dirigidas al colectivo social y a todos residentes de la ciudad, teniendo como uno de los asuntos primordiales la puesta en marcha del Centro Comercial Abierto Urbano.<\/p>\n<p>Asimismo, le presentaron al alcalde un calendario de actividades para lo que queda de ejercicio, requiriendo poder acceder a la m\u00e1xima l\u00ednea de subvenciones en cualquier organismo que sea posible. Tanto Eduardo Dol\u00f3n como Rosario Mart\u00ednez mostraron un apoyo total a la asociaci\u00f3n, insistiendo en que el trabajo de la atracci\u00f3n del peque\u00f1o y mediano comercio pasa por la concienciaci\u00f3n del propio comerciante, en detrimento de su actividad y en beneficio de las grandes \u00e1reas comerciales cercanas a la ciudad.<\/p>\n<p>La Junta Directiva de Apymeco inform\u00f3 tambi\u00e9n de las conversaciones y reuniones que est\u00e1n manteniendo con la Asociaci\u00f3n de Empresas de Hosteler\u00eda de Torrevieja y Comarca, a fin de participar mutuamente en eventos que se organicen y en un proyecto a medio plazo para unificar o confederar las diversas asociaciones de comerciantes existentes en nuestra ciudad.<\/p>\n<p>Tras m\u00e1s de dos horas, la reuni\u00f3n finaliz\u00f3 con el compromiso de ambas partes de mantener la m\u00e1xima colaboraci\u00f3n y el apoyo para intentar dinamizar y reactivar entre todos el comercio de Torrevieja, uno de los sectores productivos m\u00e1s importantes de la ciudad.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El alcalde de Torrevieja, Eduardo Dol\u00f3n, recibi\u00f3 ayer a la nueva Junta Directiva de la Asociaci\u00f3n de Peque\u00f1os y Medianos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[521],"tags":[],"class_list":["post-5729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-junta-directiva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El alcalde se re\u00fane con la nueva junta directiva de Apymeco. - APYMECO Torrevieja<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apymeco.netrotec.com\/en\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El alcalde se re\u00fane con la nueva junta directiva de Apymeco.\" \/>\n<meta property=\"og:description\" content=\"El alcalde de Torrevieja, Eduardo Dol\u00f3n, recibi\u00f3 ayer a la nueva Junta Directiva de la Asociaci\u00f3n de Peque\u00f1os y Medianos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apymeco.netrotec.com\/en\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/\" \/>\n<meta property=\"og:site_name\" content=\"APYMECO Torrevieja\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T17:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Apymeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Apymeco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/\"},\"author\":{\"name\":\"Apymeco\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/person\\\/58f3bb0f5e04e2b6067d17d05470d2dd\"},\"headline\":\"El alcalde se re\u00fane con la nueva junta directiva de Apymeco.\",\"datePublished\":\"2020-02-19T17:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/\"},\"wordCount\":373,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/86831341_1988922854586386_2391532545981284352_o.jpg\",\"articleSection\":[\"Junta directiva\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/\",\"name\":\"El alcalde se re\u00fane con la nueva junta directiva de Apymeco. - APYMECO Torrevieja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/86831341_1988922854586386_2391532545981284352_o.jpg\",\"datePublished\":\"2020-02-19T17:27:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/86831341_1988922854586386_2391532545981284352_o.jpg\",\"contentUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/86831341_1988922854586386_2391532545981284352_o.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alcalde se re\u00fane con la nueva junta directiva de Apymeco.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#website\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"name\":\"APYMECO Torrevieja\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apymeco.netrotec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#organization\",\"name\":\"APYMECO Torrevieja\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-blanco.png\",\"contentUrl\":\"https:\\\/\\\/apymeco.netrotec.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-blanco.png\",\"width\":1107,\"height\":444,\"caption\":\"APYMECO Torrevieja\"},\"image\":{\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apymeco.netrotec.com\\\/#\\\/schema\\\/person\\\/58f3bb0f5e04e2b6067d17d05470d2dd\",\"name\":\"Apymeco\",\"url\":\"https:\\\/\\\/apymeco.netrotec.com\\\/en\\\/author\\\/apymeco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco. - APYMECO Torrevieja","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apymeco.netrotec.com\/en\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/","og_locale":"en_GB","og_type":"article","og_title":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco.","og_description":"El alcalde de Torrevieja, Eduardo Dol\u00f3n, recibi\u00f3 ayer a la nueva Junta Directiva de la Asociaci\u00f3n de Peque\u00f1os y Medianos [&hellip;]","og_url":"https:\/\/apymeco.netrotec.com\/en\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/","og_site_name":"APYMECO Torrevieja","article_published_time":"2020-02-19T17:27:00+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg","type":"image\/jpeg"}],"author":"Apymeco","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Apymeco","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#article","isPartOf":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/"},"author":{"name":"Apymeco","@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/person\/58f3bb0f5e04e2b6067d17d05470d2dd"},"headline":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco.","datePublished":"2020-02-19T17:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/"},"wordCount":373,"commentCount":0,"publisher":{"@id":"https:\/\/apymeco.netrotec.com\/#organization"},"image":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#primaryimage"},"thumbnailUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg","articleSection":["Junta directiva"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/","url":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/","name":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco. - APYMECO Torrevieja","isPartOf":{"@id":"https:\/\/apymeco.netrotec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#primaryimage"},"image":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#primaryimage"},"thumbnailUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg","datePublished":"2020-02-19T17:27:00+00:00","breadcrumb":{"@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#primaryimage","url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg","contentUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2020\/02\/86831341_1988922854586386_2391532545981284352_o.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/apymeco.netrotec.com\/el-alcalde-se-reune-con-la-nueva-junta-directiva-de-apymeco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apymeco.netrotec.com\/"},{"@type":"ListItem","position":2,"name":"El alcalde se re\u00fane con la nueva junta directiva de Apymeco."}]},{"@type":"WebSite","@id":"https:\/\/apymeco.netrotec.com\/#website","url":"https:\/\/apymeco.netrotec.com\/","name":"APYMECO Torrevieja","description":"","publisher":{"@id":"https:\/\/apymeco.netrotec.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apymeco.netrotec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/apymeco.netrotec.com\/#organization","name":"APYMECO Torrevieja","url":"https:\/\/apymeco.netrotec.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/logo\/image\/","url":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/logo-blanco.png","contentUrl":"https:\/\/apymeco.netrotec.com\/wp-content\/uploads\/2026\/06\/logo-blanco.png","width":1107,"height":444,"caption":"APYMECO Torrevieja"},"image":{"@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/apymeco.netrotec.com\/#\/schema\/person\/58f3bb0f5e04e2b6067d17d05470d2dd","name":"Apymeco","url":"https:\/\/apymeco.netrotec.com\/en\/author\/apymeco\/"}]}},"_links":{"self":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/posts\/5729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/comments?post=5729"}],"version-history":[{"count":0,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/posts\/5729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/media\/5730"}],"wp:attachment":[{"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/media?parent=5729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/categories?post=5729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apymeco.netrotec.com\/en\/wp-json\/wp\/v2\/tags?post=5729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}